{"id":66450,"date":"2026-07-15T05:21:27","date_gmt":"2026-07-15T05:21:27","guid":{"rendered":"https:\/\/mexicopublica.mx\/?page_id=66450"},"modified":"2026-07-15T17:16:42","modified_gmt":"2026-07-15T17:16:42","slug":"jalisco-15-de-julio","status":"publish","type":"page","link":"https:\/\/mexicopublica.mx\/en\/jalisco-15-de-julio\/","title":{"rendered":"Jalisco 15 De Julio"},"content":{"rendered":"<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@gmpdiario\/video\/7662784951904914708\" data-video-id=\"7662784951904914708\" style=\"max-width: 605px;min-width: 325px;\" > <section> <a target=\"_blank\" title=\"@gmpdiario\" href=\"https:\/\/www.tiktok.com\/@gmpdiario?refer=embed\">@gmpdiario<\/a> <p>Jalisco 15 De Julio <\/p> <a target=\"_blank\" title=\"\u266c sonido original - Grupo M\u00e9xico Publica\" href=\"https:\/\/www.tiktok.com\/music\/sonido-original-7662785000400407314?refer=embed\">\u266c sonido original &#8211; Grupo M\u00e9xico Publica<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>","protected":false},"excerpt":{"rendered":"<p>@gmpdiario Jalisco 15 De Julio \u266c sonido original &#8211; Grupo M\u00e9xico Publica<\/p>","protected":false},"author":7,"featured_media":66417,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-66450","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jalisco 15 De Julio - Grupo M\u00e9xico Publica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mexicopublica.mx\/en\/jalisco-15-de-julio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jalisco 15 De Julio - Grupo M\u00e9xico Publica\" \/>\n<meta property=\"og:description\" content=\"@gmpdiario Jalisco 15 De Julio \u266c sonido original &#8211; Grupo M\u00e9xico Publica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mexicopublica.mx\/en\/jalisco-15-de-julio\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo M\u00e9xico Publica\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T17:16:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/48bffe5d-14c8-400e-8bb2-54ac32229948.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"288\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/jalisco-15-de-julio\\\/\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/jalisco-15-de-julio\\\/\",\"name\":\"Jalisco 15 De Julio - Grupo M\u00e9xico Publica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/jalisco-15-de-julio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/jalisco-15-de-julio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/48bffe5d-14c8-400e-8bb2-54ac32229948.jpeg\",\"datePublished\":\"2026-07-15T05:21:27+00:00\",\"dateModified\":\"2026-07-15T17:16:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/jalisco-15-de-julio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mexicopublica.mx\\\/jalisco-15-de-julio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/jalisco-15-de-julio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/48bffe5d-14c8-400e-8bb2-54ac32229948.jpeg\",\"contentUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/48bffe5d-14c8-400e-8bb2-54ac32229948.jpeg\",\"width\":288,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/jalisco-15-de-julio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mexicopublica.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jalisco 15 De Julio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#website\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/\",\"name\":\"M\u00e9xico Publica\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mexicopublica.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#organization\",\"name\":\"M\u00e9xico Publica\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-gmp-web.webp\",\"contentUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-gmp-web.webp\",\"width\":1200,\"height\":1200,\"caption\":\"M\u00e9xico Publica\"},\"image\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jalisco 15 De Julio - Grupo M\u00e9xico Publica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mexicopublica.mx\/en\/jalisco-15-de-julio\/","og_locale":"en_US","og_type":"article","og_title":"Jalisco 15 De Julio - Grupo M\u00e9xico Publica","og_description":"@gmpdiario Jalisco 15 De Julio \u266c sonido original &#8211; Grupo M\u00e9xico Publica","og_url":"https:\/\/mexicopublica.mx\/en\/jalisco-15-de-julio\/","og_site_name":"Grupo M\u00e9xico Publica","article_modified_time":"2026-07-15T17:16:42+00:00","og_image":[{"width":288,"height":512,"url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/48bffe5d-14c8-400e-8bb2-54ac32229948.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mexicopublica.mx\/jalisco-15-de-julio\/","url":"https:\/\/mexicopublica.mx\/jalisco-15-de-julio\/","name":"Jalisco 15 De Julio - Grupo M\u00e9xico Publica","isPartOf":{"@id":"https:\/\/mexicopublica.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mexicopublica.mx\/jalisco-15-de-julio\/#primaryimage"},"image":{"@id":"https:\/\/mexicopublica.mx\/jalisco-15-de-julio\/#primaryimage"},"thumbnailUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/48bffe5d-14c8-400e-8bb2-54ac32229948.jpeg","datePublished":"2026-07-15T05:21:27+00:00","dateModified":"2026-07-15T17:16:42+00:00","breadcrumb":{"@id":"https:\/\/mexicopublica.mx\/jalisco-15-de-julio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mexicopublica.mx\/jalisco-15-de-julio\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mexicopublica.mx\/jalisco-15-de-julio\/#primaryimage","url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/48bffe5d-14c8-400e-8bb2-54ac32229948.jpeg","contentUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/48bffe5d-14c8-400e-8bb2-54ac32229948.jpeg","width":288,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/mexicopublica.mx\/jalisco-15-de-julio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mexicopublica.mx\/"},{"@type":"ListItem","position":2,"name":"Jalisco 15 De Julio"}]},{"@type":"WebSite","@id":"https:\/\/mexicopublica.mx\/#website","url":"https:\/\/mexicopublica.mx\/","name":"M\u00e9xico Publica","description":"Noticias","publisher":{"@id":"https:\/\/mexicopublica.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mexicopublica.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mexicopublica.mx\/#organization","name":"M\u00e9xico Publica","url":"https:\/\/mexicopublica.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mexicopublica.mx\/#\/schema\/logo\/image\/","url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2025\/08\/logo-gmp-web.webp","contentUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2025\/08\/logo-gmp-web.webp","width":1200,"height":1200,"caption":"M\u00e9xico Publica"},"image":{"@id":"https:\/\/mexicopublica.mx\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/comments?post=66450"}],"version-history":[{"count":3,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66450\/revisions"}],"predecessor-version":[{"id":66512,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66450\/revisions\/66512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/media\/66417"}],"wp:attachment":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/media?parent=66450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}