{"id":66524,"date":"2026-07-15T18:39:15","date_gmt":"2026-07-15T18:39:15","guid":{"rendered":"https:\/\/mexicopublica.mx\/?page_id=66524"},"modified":"2026-07-15T18:39:15","modified_gmt":"2026-07-15T18:39:15","slug":"encuesta-zapopan","status":"publish","type":"page","link":"https:\/\/mexicopublica.mx\/en\/encuesta-zapopan\/","title":{"rendered":"Encuesta ZAPOPAN"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie-1024x684.webp\" alt=\"\" class=\"wp-image-66525\" srcset=\"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie-1024x684.webp 1024w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie-300x201.webp 300w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie-768x513.webp 768w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie-18x12.webp 18w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie-450x301.webp 450w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie-700x468.webp 700w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><div class='bootstrap-yop yop-poll-mc'>\n\t\t\t\t\t\t\t<div class=\"basic-yop-poll-container\" style=\"background-color:#ffffff; border:1px; border-style:solid; border-color:#000000; border-radius:5px; padding:10px 10px;\" data-id=\"28\" data-temp=\"basic-pretty\" data-skin=\"square\" data-cscheme=\"green\" data-cap=\"0\" data-access=\"guest\" data-tid=\"\" data-uid=\"d60a0309efee3d95a569cc663e9e26be\" data-pid=\"66524\" data-resdet=\"votes-number,percentages\" data-show-results-to=\"guest\" data-show-results-moment=\"before-vote,after-vote,after-end-date\" data-show-results-only=\"false\" data-show-message=\"true\" data-show-results-as=\"bar\" data-sort-results-by=\"as-defined\" data-sort-results-rule=\"asc\"data-is-ended=\"0\" data-percentages-decimals=\"2\" data-gdpr=\"no\" data-gdpr-sol=\"consent\" data-css=\".basic-yop-poll-container[data-uid] .basic-vote {\n\t\t\t\t\t\t\t\t\ttext-align: center;\n\t\t\t\t\t\t\t\t}\" data-counter=\"0\" data-load-with=\"1\" data-notification-section=\"top\"><div class=\"row\"><div class=\"col-md-12\"><div class=\"basic-inner\"><div class=\"basic-message hide\" style=\"border-left: 10px solid #008000; padding: 0px 10px;\" data-error=\"#ff0000\" data-success=\"#008000\"><p class=\"basic-message-text\" style=\"color:#000000; font-size:14px; font-weight:normal;\"><\/p><\/div><div class=\"basic-overlay hide\"><div class=\"basic-vote-options\"><\/div><div class=\"basic-preloader\"><div class=\"basic-windows8\"><div class=\"basic-wBall basic-wBall_1\"><div class=\"basic-wInnerBall\"><\/div><\/div><div class=\"basic-wBall basic-wBall_2\"><div class=\"basic-wInnerBall\"><\/div><\/div><div class=\"basic-wBall basic-wBall_3\"><div class=\"basic-wInnerBall\"><\/div><\/div><div class=\"basic-wBall basic-wBall_4\"><div class=\"basic-wInnerBall\"><\/div><\/div><div class=\"basic-wBall basic-wBall_5\"><div class=\"basic-wInnerBall\"><\/div><\/div><\/div><\/div><\/div><form class=\"basic-form\"><input type=\"hidden\" name=\"_token\" value=\"027b14752b\" autocomplete=\"off\"><div class=\"basic-elements\"><div class=\"basic-element basic-question basic-question-text-vertical\" data-id=\"28\" data-uid=\"9884d70c3fbd51854d02cac10a01b31d\" data-type=\"question\" data-question-type=\"text\" data-required=\"yes\" data-allow-multiple=\"no\" data-min=\"1\" data-max=\"1\" data-display=\"vertical\" data-colnum=\"\" data-display-others=\"no\" data-others-color=\"\" data-others=\"\" data-others-max-chars=\"0\"><div class=\"basic-question-title\"><h5 style=\"color:#000000; font-size:16px; font-weight:normal; text-align:center;\">\u00bfC\u00f3mo califica la gesti\u00f3n del presidente municipal Juan Jos\u00e9 Frangie?<\/h5><\/div><ul class=\"basic-answers\"><li class=\"basic-answer\" style=\"padding:0px 0px;\" data-id=\"115\" data-type=\"text\" data-vn=\"33\" data-color=\"#000000\" data-make-link=\"no\" data-link=\"\"><div class=\"basic-answer-content basic-text-vertical\"><label for=\"answer[115]\" class=\"basic-answer-label\"><input type=\"radio\" id=\"answer[115]\" name=\"answer[28]\" value=\"115\"><span class=\"basic-text\" style=\"color: #000000; font-size: 14px; font-weight: normal;\">EXCELENTE<\/span><\/label><\/div><\/li><li class=\"basic-answer\" style=\"padding:0px 0px;\" data-id=\"113\" data-type=\"text\" data-vn=\"56\" data-color=\"#000000\" data-make-link=\"no\" data-link=\"\"><div class=\"basic-answer-content basic-text-vertical\"><label for=\"answer[113]\" class=\"basic-answer-label\"><input type=\"radio\" id=\"answer[113]\" name=\"answer[28]\" value=\"113\"><span class=\"basic-text\" style=\"color: #000000; font-size: 14px; font-weight: normal;\">BUENA<\/span><\/label><\/div><\/li><li class=\"basic-answer\" style=\"padding:0px 0px;\" data-id=\"114\" data-type=\"text\" data-vn=\"13\" data-color=\"#000000\" data-make-link=\"no\" data-link=\"\"><div class=\"basic-answer-content basic-text-vertical\"><label for=\"answer[114]\" class=\"basic-answer-label\"><input type=\"radio\" id=\"answer[114]\" name=\"answer[28]\" value=\"114\"><span class=\"basic-text\" style=\"color: #000000; font-size: 14px; font-weight: normal;\">MALA<\/span><\/label><\/div><\/li><\/ul><\/div><div class=\"clearfix\"><\/div><\/div><div class=\"basic-stats text-center\"><span class=\"basic-stats-votes\"><span class=\"basic-stats-votes-number\">102<\/span><span class=\"basic-stats-votes-text\">&nbsp;votos<\/span><\/span><span class=\"basic-stats-separator\">&nbsp;&middot;&nbsp;<\/span><span class=\"basic-stats-answers\"><span class=\"basic-stats-answers-number\">102<\/span><span class=\"basic-stats-answers-text\">&nbsp;answers<\/span><\/span><\/div><div class=\"basic-vote\"><a href=\"#\" class=\"button basic-vote-button\" role=\"button\" style=\"background:#ffffff; border:1px; border-style: solid; border-color:#000000; border-radius:0px; padding:5px 10px; color:#000000; font-size:14px; font-weight:normal;\">VotAR<\/a><a href=\"#\" class=\"button basic-results-button\" role=\"button\" style=\"background:#ffffff; border:1px; border-style: solid; border-color:#000000; border-radius:0px; padding:5px 10px; color:#000000; font-size:14px; font-weight:normal;\">Resultados<\/a><\/div><\/form><\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":66525,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-66524","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encuesta ZAPOPAN - Grupo M\u00e9xico Publica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mexicopublica.mx\/en\/encuesta-zapopan\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuesta ZAPOPAN - Grupo M\u00e9xico Publica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mexicopublica.mx\/en\/encuesta-zapopan\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo M\u00e9xico Publica\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"802\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-zapopan\\\/\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-zapopan\\\/\",\"name\":\"Encuesta ZAPOPAN - Grupo M\u00e9xico Publica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-zapopan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-zapopan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/frangie.webp\",\"datePublished\":\"2026-07-15T18:39:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-zapopan\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-zapopan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-zapopan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/frangie.webp\",\"contentUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/frangie.webp\",\"width\":1200,\"height\":802},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-zapopan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mexicopublica.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuesta ZAPOPAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#website\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/\",\"name\":\"M\u00e9xico Publica\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mexicopublica.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#organization\",\"name\":\"M\u00e9xico Publica\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-gmp-web.webp\",\"contentUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-gmp-web.webp\",\"width\":1200,\"height\":1200,\"caption\":\"M\u00e9xico Publica\"},\"image\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuesta ZAPOPAN - Grupo M\u00e9xico Publica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mexicopublica.mx\/en\/encuesta-zapopan\/","og_locale":"en_US","og_type":"article","og_title":"Encuesta ZAPOPAN - Grupo M\u00e9xico Publica","og_url":"https:\/\/mexicopublica.mx\/en\/encuesta-zapopan\/","og_site_name":"Grupo M\u00e9xico Publica","og_image":[{"width":1200,"height":802,"url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mexicopublica.mx\/encuesta-zapopan\/","url":"https:\/\/mexicopublica.mx\/encuesta-zapopan\/","name":"Encuesta ZAPOPAN - Grupo M\u00e9xico Publica","isPartOf":{"@id":"https:\/\/mexicopublica.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mexicopublica.mx\/encuesta-zapopan\/#primaryimage"},"image":{"@id":"https:\/\/mexicopublica.mx\/encuesta-zapopan\/#primaryimage"},"thumbnailUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie.webp","datePublished":"2026-07-15T18:39:15+00:00","breadcrumb":{"@id":"https:\/\/mexicopublica.mx\/encuesta-zapopan\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mexicopublica.mx\/encuesta-zapopan\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mexicopublica.mx\/encuesta-zapopan\/#primaryimage","url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie.webp","contentUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/frangie.webp","width":1200,"height":802},{"@type":"BreadcrumbList","@id":"https:\/\/mexicopublica.mx\/encuesta-zapopan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mexicopublica.mx\/"},{"@type":"ListItem","position":2,"name":"Encuesta ZAPOPAN"}]},{"@type":"WebSite","@id":"https:\/\/mexicopublica.mx\/#website","url":"https:\/\/mexicopublica.mx\/","name":"M\u00e9xico Publica","description":"Noticias","publisher":{"@id":"https:\/\/mexicopublica.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mexicopublica.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mexicopublica.mx\/#organization","name":"M\u00e9xico Publica","url":"https:\/\/mexicopublica.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mexicopublica.mx\/#\/schema\/logo\/image\/","url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2025\/08\/logo-gmp-web.webp","contentUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2025\/08\/logo-gmp-web.webp","width":1200,"height":1200,"caption":"M\u00e9xico Publica"},"image":{"@id":"https:\/\/mexicopublica.mx\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/comments?post=66524"}],"version-history":[{"count":1,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66524\/revisions"}],"predecessor-version":[{"id":66526,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66524\/revisions\/66526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/media\/66525"}],"wp:attachment":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/media?parent=66524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}