{"id":66532,"date":"2026-07-15T18:51:18","date_gmt":"2026-07-15T18:51:18","guid":{"rendered":"https:\/\/mexicopublica.mx\/?page_id=66532"},"modified":"2026-07-15T18:51:19","modified_gmt":"2026-07-15T18:51:19","slug":"encuesta-tlajomulco","status":"publish","type":"page","link":"https:\/\/mexicopublica.mx\/en\/encuesta-tlajomulco\/","title":{"rendered":"Encuesta Tlajomulco"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo-1024x684.webp\" alt=\"\" class=\"wp-image-66529\" srcset=\"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo-1024x684.webp 1024w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo-300x201.webp 300w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo-768x513.webp 768w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo-18x12.webp 18w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo-450x301.webp 450w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo-700x468.webp 700w, https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><div class='bootstrap-yop yop-poll-mc'>\n\t\t\t\t\t\t\t<div class=\"basic-yop-poll-container\" style=\"background-color:#ffffff; border:1px; border-style:solid; border-color:#000000; border-radius:0px; padding:10px 10px;\" data-id=\"30\" data-temp=\"basic-pretty\" data-skin=\"square\" data-cscheme=\"green\" data-cap=\"0\" data-access=\"guest\" data-tid=\"\" data-uid=\"f01777fd3d452d41661e54e92396b58b\" data-pid=\"66532\" data-resdet=\"votes-number,percentages\" data-show-results-to=\"guest\" data-show-results-moment=\"before-vote,after-vote,after-end-date\" data-show-results-only=\"false\" data-show-message=\"true\" data-show-results-as=\"bar\" data-sort-results-by=\"as-defined\" data-sort-results-rule=\"asc\"data-is-ended=\"0\" data-percentages-decimals=\"2\" data-gdpr=\"no\" data-gdpr-sol=\"consent\" data-css=\".basic-yop-poll-container[data-uid] .basic-vote {\n\t\t\t\t\t\t\t\t\ttext-align: center;\n\t\t\t\t\t\t\t\t}\" data-counter=\"0\" data-load-with=\"1\" data-notification-section=\"top\"><div class=\"row\"><div class=\"col-md-12\"><div class=\"basic-inner\"><div class=\"basic-message hide\" style=\"border-left: 10px solid #008000; padding: 0px 10px;\" data-error=\"#ff0000\" data-success=\"#008000\"><p class=\"basic-message-text\" style=\"color:#000000; font-size:14px; font-weight:normal;\"><\/p><\/div><div class=\"basic-overlay hide\"><div class=\"basic-vote-options\"><\/div><div class=\"basic-preloader\"><div class=\"basic-windows8\"><div class=\"basic-wBall basic-wBall_1\"><div class=\"basic-wInnerBall\"><\/div><\/div><div class=\"basic-wBall basic-wBall_2\"><div class=\"basic-wInnerBall\"><\/div><\/div><div class=\"basic-wBall basic-wBall_3\"><div class=\"basic-wInnerBall\"><\/div><\/div><div class=\"basic-wBall basic-wBall_4\"><div class=\"basic-wInnerBall\"><\/div><\/div><div class=\"basic-wBall basic-wBall_5\"><div class=\"basic-wInnerBall\"><\/div><\/div><\/div><\/div><\/div><form class=\"basic-form\"><input type=\"hidden\" name=\"_token\" value=\"43e01b5918\" autocomplete=\"off\"><div class=\"basic-elements\"><div class=\"basic-element basic-question basic-question-text-vertical\" data-id=\"30\" data-uid=\"54719f890b4e736f322df7f912d9e518\" data-type=\"question\" data-question-type=\"text\" data-required=\"yes\" data-allow-multiple=\"no\" data-min=\"1\" data-max=\"1\" data-display=\"vertical\" data-colnum=\"\" data-display-others=\"no\" data-others-color=\"\" data-others=\"\" data-others-max-chars=\"0\"><div class=\"basic-question-title\"><h5 style=\"color:#000000; font-size:16px; font-weight:normal; text-align:left;\">\u00bfC\u00f3mo califica la gesti\u00f3n del presidente municipal Gerardo Quirino?<\/h5><\/div><ul class=\"basic-answers\"><li class=\"basic-answer\" style=\"padding:0px 0px;\" data-id=\"121\" data-type=\"text\" data-vn=\"3\" data-color=\"#000000\" data-make-link=\"no\" data-link=\"\"><div class=\"basic-answer-content basic-text-vertical\"><label for=\"answer[121]\" class=\"basic-answer-label\"><input type=\"radio\" id=\"answer[121]\" name=\"answer[30]\" value=\"121\"><span class=\"basic-text\" style=\"color: #000000; font-size: 14px; font-weight: normal;\">EXCELENTE<\/span><\/label><\/div><\/li><li class=\"basic-answer\" style=\"padding:0px 0px;\" data-id=\"119\" data-type=\"text\" data-vn=\"52\" data-color=\"#000000\" data-make-link=\"no\" data-link=\"\"><div class=\"basic-answer-content basic-text-vertical\"><label for=\"answer[119]\" class=\"basic-answer-label\"><input type=\"radio\" id=\"answer[119]\" name=\"answer[30]\" value=\"119\"><span class=\"basic-text\" style=\"color: #000000; font-size: 14px; font-weight: normal;\">BUENA<\/span><\/label><\/div><\/li><li class=\"basic-answer\" style=\"padding:0px 0px;\" data-id=\"120\" data-type=\"text\" data-vn=\"34\" data-color=\"#000000\" data-make-link=\"no\" data-link=\"\"><div class=\"basic-answer-content basic-text-vertical\"><label for=\"answer[120]\" class=\"basic-answer-label\"><input type=\"radio\" id=\"answer[120]\" name=\"answer[30]\" value=\"120\"><span class=\"basic-text\" style=\"color: #000000; font-size: 14px; font-weight: normal;\">MALA<\/span><\/label><\/div><\/li><\/ul><\/div><div class=\"clearfix\"><\/div><\/div><div class=\"basic-stats text-center\"><span class=\"basic-stats-votes\"><span class=\"basic-stats-votes-number\">89<\/span><span class=\"basic-stats-votes-text\">&nbsp;votos<\/span><\/span><span class=\"basic-stats-separator\">&nbsp;&middot;&nbsp;<\/span><span class=\"basic-stats-answers\"><span class=\"basic-stats-answers-number\">89<\/span><span class=\"basic-stats-answers-text\">&nbsp;answers<\/span><\/span><\/div><div class=\"basic-vote\"><a href=\"#\" class=\"button basic-vote-button\" role=\"button\" style=\"background:#ffffff; border:1px; border-style: solid; border-color:#000000; border-radius:0px; padding:5px 10px; color:#000000; font-size:14px; font-weight:normal;\">VotAR<\/a><a href=\"#\" class=\"button basic-results-button\" role=\"button\" style=\"background:#ffffff; border:1px; border-style: solid; border-color:#000000; border-radius:0px; padding:5px 10px; color:#000000; font-size:14px; font-weight:normal;\">Resultados<\/a><\/div><\/form><\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":66529,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-66532","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encuesta Tlajomulco - Grupo M\u00e9xico Publica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mexicopublica.mx\/en\/encuesta-tlajomulco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuesta Tlajomulco - Grupo M\u00e9xico Publica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mexicopublica.mx\/en\/encuesta-tlajomulco\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo M\u00e9xico Publica\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T18:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"802\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-tlajomulco\\\/\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-tlajomulco\\\/\",\"name\":\"Encuesta Tlajomulco - Grupo M\u00e9xico Publica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-tlajomulco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-tlajomulco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/gerardo.webp\",\"datePublished\":\"2026-07-15T18:51:18+00:00\",\"dateModified\":\"2026-07-15T18:51:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-tlajomulco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-tlajomulco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-tlajomulco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/gerardo.webp\",\"contentUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/gerardo.webp\",\"width\":1200,\"height\":802},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/encuesta-tlajomulco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mexicopublica.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuesta Tlajomulco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#website\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/\",\"name\":\"M\u00e9xico Publica\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mexicopublica.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#organization\",\"name\":\"M\u00e9xico Publica\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-gmp-web.webp\",\"contentUrl\":\"https:\\\/\\\/mexicopublica.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-gmp-web.webp\",\"width\":1200,\"height\":1200,\"caption\":\"M\u00e9xico Publica\"},\"image\":{\"@id\":\"https:\\\/\\\/mexicopublica.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuesta Tlajomulco - Grupo M\u00e9xico Publica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mexicopublica.mx\/en\/encuesta-tlajomulco\/","og_locale":"en_US","og_type":"article","og_title":"Encuesta Tlajomulco - Grupo M\u00e9xico Publica","og_url":"https:\/\/mexicopublica.mx\/en\/encuesta-tlajomulco\/","og_site_name":"Grupo M\u00e9xico Publica","article_modified_time":"2026-07-15T18:51:19+00:00","og_image":[{"width":1200,"height":802,"url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mexicopublica.mx\/encuesta-tlajomulco\/","url":"https:\/\/mexicopublica.mx\/encuesta-tlajomulco\/","name":"Encuesta Tlajomulco - Grupo M\u00e9xico Publica","isPartOf":{"@id":"https:\/\/mexicopublica.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mexicopublica.mx\/encuesta-tlajomulco\/#primaryimage"},"image":{"@id":"https:\/\/mexicopublica.mx\/encuesta-tlajomulco\/#primaryimage"},"thumbnailUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo.webp","datePublished":"2026-07-15T18:51:18+00:00","dateModified":"2026-07-15T18:51:19+00:00","breadcrumb":{"@id":"https:\/\/mexicopublica.mx\/encuesta-tlajomulco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mexicopublica.mx\/encuesta-tlajomulco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mexicopublica.mx\/encuesta-tlajomulco\/#primaryimage","url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo.webp","contentUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2026\/07\/gerardo.webp","width":1200,"height":802},{"@type":"BreadcrumbList","@id":"https:\/\/mexicopublica.mx\/encuesta-tlajomulco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mexicopublica.mx\/"},{"@type":"ListItem","position":2,"name":"Encuesta Tlajomulco"}]},{"@type":"WebSite","@id":"https:\/\/mexicopublica.mx\/#website","url":"https:\/\/mexicopublica.mx\/","name":"M\u00e9xico Publica","description":"Noticias","publisher":{"@id":"https:\/\/mexicopublica.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mexicopublica.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mexicopublica.mx\/#organization","name":"M\u00e9xico Publica","url":"https:\/\/mexicopublica.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mexicopublica.mx\/#\/schema\/logo\/image\/","url":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2025\/08\/logo-gmp-web.webp","contentUrl":"https:\/\/mexicopublica.mx\/wp-content\/uploads\/2025\/08\/logo-gmp-web.webp","width":1200,"height":1200,"caption":"M\u00e9xico Publica"},"image":{"@id":"https:\/\/mexicopublica.mx\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/comments?post=66532"}],"version-history":[{"count":1,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66532\/revisions"}],"predecessor-version":[{"id":66533,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/pages\/66532\/revisions\/66533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/media\/66529"}],"wp:attachment":[{"href":"https:\/\/mexicopublica.mx\/en\/wp-json\/wp\/v2\/media?parent=66532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}